{"id":1637,"date":"2015-06-01T19:22:37","date_gmt":"2015-06-01T19:22:37","guid":{"rendered":"https:\/\/judicialconductboardofpa.org\/relaciones-publicas\/"},"modified":"2023-07-20T19:47:42","modified_gmt":"2023-07-20T19:47:42","slug":"relaciones-publicas","status":"publish","type":"page","link":"https:\/\/judicialconductboardofpa.org\/es\/relaciones-publicas\/","title":{"rendered":"Relaciones p\u00fablicas"},"content":{"rendered":"<p>La misi\u00f3n de la Junta es, como la de todo el sistema judicial de Pensilvania, velar por que la Commonwealth sea una sociedad justa. Los ciudadanos de la Commonwealth tienen derecho a esperar de los jueces un alto nivel de \u00e9tica, y la Junta es una parte importante del sistema que garantiza el mantenimiento de dicho nivel.<\/p>\n<p>La Asesora Jur\u00eddica Principal del Consejo, Melissa L. Norton, y los miembros de su personal son defensores eficaces y experimentados de la \u00e9tica judicial. Siempre que es posible, est\u00e1n disponibles para dar charlas, tanto para informar como para aprender de los ciudadanos, estudiantes de Derecho y abogados interesados.<\/p>\n<p>Si desea concertar una cita, env\u00ede un correo electr\u00f3nico <a href=\"mailto:ContactUs@jcbpa.org\">a ContactUs@JCBPA.org<\/a> o llame al (717) 234-7911. Nota: Se ruega reservar con antelaci\u00f3n, ya que los horarios pueden llenarse bastante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La misi\u00f3n de la Junta es, como la de todo el sistema judicial de Pensilvania, velar por que la Commonwealth sea una sociedad justa. Los ciudadanos de la Commonwealth tienen derecho a esperar de los jueces un alto nivel de \u00e9tica, y la Junta es una parte importante del sistema que garantiza el mantenimiento de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-full.php","meta":{"footnotes":""},"class_list":["post-1637","page","type-page","status-publish","hentry","post"],"_links":{"self":[{"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/pages\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":2,"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/pages\/1637\/revisions"}],"predecessor-version":[{"id":1806,"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/pages\/1637\/revisions\/1806"}],"wp:attachment":[{"href":"https:\/\/judicialconductboardofpa.org\/es\/wp-json\/wp\/v2\/media?parent=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}